{"id":11730,"date":"2025-11-18T00:15:43","date_gmt":"2025-11-18T05:15:43","guid":{"rendered":"https:\/\/cartagenaaldia.com\/?p=11730"},"modified":"2025-11-18T00:15:44","modified_gmt":"2025-11-18T05:15:44","slug":"eleccion-de-maria-antonia-como-senorita-colombia-emociona-al-pais","status":"publish","type":"post","link":"https:\/\/cartagenaaldia.com\/index.php\/2025\/11\/18\/eleccion-de-maria-antonia-como-senorita-colombia-emociona-al-pais\/","title":{"rendered":"Elecci\u00f3n de Mar\u00eda Antonia como Se\u00f1orita Colombia emociona al p\u00e1is"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>La elecci\u00f3n de la nueva Se\u00f1orita Colombia exalta liderazgo femenino y destaca la fuerza de la regi\u00f3n Caribe y Pacifica<\/strong><\/h2>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>La noche de elecci\u00f3n y coronaci\u00f3n del Concurso Nacional de Belleza\u00ae 2025-2026 qued\u00f3 marcada por un momento que uni\u00f3 tradici\u00f3n, emoci\u00f3n y orgullo nacional cuando <strong>Mar\u00eda Antonia Mosquera, se\u00f1orita Valle, fue elegida como la nueva reina de Colombia<\/strong>. La decisi\u00f3n estuvo a cargo de cuatro mujeres que representan la historia y el legado del certamen: <strong>Andrea Nocetti, Catherine Daza, Melissa Var\u00f3n y Sof\u00eda Os\u00edo<\/strong>, exreinas que han dejado huella durante los 91 a\u00f1os de existencia del concurso.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/cartagenaaldia.com\/wp-content\/uploads\/2025\/11\/CNB-Senorita-Colombia-Antonia-Mosquera-769x1024.webp\" alt=\"\" class=\"wp-image-11733\"\/><figcaption class=\"wp-element-caption\">Srta. Colombia 2025-26 Antonia Mosquera. Foto Cortes\u00eda: CNB<\/figcaption><\/figure><\/div>\n\n\n<p>El escenario del <strong>Centro de Convenciones de Las Am\u00e9ricas<\/strong> fue testigo de una velada inolvidable, llena de elegancia, emoci\u00f3n y un espect\u00e1culo musical cargado de esencia cartagenera, guiado por la voz \u00fanica de <strong>Juan Carlos Coronel<\/strong>, quien una vez m\u00e1s reafirm\u00f3 su lugar como referente de la cultura nacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>El triunfo de Mar\u00eda Antonia Mosquera emociona a Colombia<\/strong><\/h2>\n\n\n\n<p>Desde el primer instante, la elecci\u00f3n de Mar\u00eda Antonia Mosquera gener\u00f3 una respuesta llena de orgullo y entusiasmo. La nueva soberana, visiblemente conmovida, dedic\u00f3 su victoria a las personas que considera el motor m\u00e1s importante de su vida: <strong>su madre y su hermana<\/strong>. \u201cMe han acompa\u00f1ado en todo, han sido mi motor m\u00e1s grande\u201d, expres\u00f3 con profunda gratitud.<\/p>\n\n\n\n<p>La reina tambi\u00e9n dirigi\u00f3 un mensaje al Valle del Cauca y a todo el pa\u00eds, resaltando que el apoyo del p\u00fablico fue determinante para alcanzar la corona. Con emoci\u00f3n, afirm\u00f3:<br><strong>\u201cHoy m\u00e1s que nunca siento todo su apoyo (\u2026) leerlos y sentir su energ\u00eda ha sido el motor m\u00e1s importante para llegar aqu\u00ed.\u201d<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/cartagenaaldia.com\/wp-content\/uploads\/2025\/11\/CNB-Srta-Colombia-Imposicion-Corona-769x1024.webp\" alt=\"\" class=\"wp-image-11735\"\/><figcaption class=\"wp-element-caption\">CNB Srta Colombia Imposicion Corona. Foto Cortes\u00eda: CNB<\/figcaption><\/figure><\/div>\n\n\n<p>Sus palabras reflejaron la conexi\u00f3n que logr\u00f3 con el p\u00fablico a lo largo del concurso y el compromiso que ahora adquiere como representante de Colombia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un p\u00f3dium que une las costas del pa\u00eds<\/strong><\/h2>\n\n\n\n<p>El Concurso Nacional de Belleza\u00ae destac\u00f3 este a\u00f1o por la diversidad y la fuerza de sus finalistas. El <strong>p\u00f3dium Real<\/strong> qued\u00f3 conformado por representantes de las costas del Caribe, al Pac\u00edfico del pa\u00eds.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Virreina Nacional:<\/strong> Valentina Olano, Atl\u00e1ntico<\/li>\n\n\n\n<li><strong>Primera Princesa:<\/strong> Kristy Moreno, Choc\u00f3<\/li>\n\n\n\n<li><strong>Segunda Princesa:<\/strong> Martha Otero, C\u00f3rdoba<\/li>\n\n\n\n<li><strong>Tercera Princesa:<\/strong> Mar\u00eda Jos\u00e9 Ayazo, Bol\u00edvar<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" width=\"769\" height=\"1024\" src=\"https:\/\/cartagenaaldia.com\/wp-content\/uploads\/2025\/11\/CNB-Podium-Real-769x1024.webp\" alt=\"\" class=\"wp-image-11736\"\/><figcaption class=\"wp-element-caption\">P\u00f3dium Real 2025-26 Concurso Nacional de Belleza: Foto Cortes\u00eda: CNB<\/figcaption><\/figure><\/div>\n\n\n<p>Esta distribuci\u00f3n regional resalta la variedad cultural, \u00e9tnica y est\u00e9tica de Colombia, fortaleciendo la identidad de un concurso que sigue siendo referente nacional e internacional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Una noche hist\u00f3rica en un nuevo escenario<\/strong><\/h2>\n\n\n\n<p>Por primera vez, el certamen se realiz\u00f3 en el <strong>Centro de Convenciones de Las Am\u00e9ricas<\/strong>, una apuesta que refresc\u00f3 la experiencia y brind\u00f3 un ambiente de gala y sofisticaci\u00f3n. El p\u00fablico asistente disfrut\u00f3 de una producci\u00f3n impecable en la que cada detalle contribuy\u00f3 a la construcci\u00f3n de un espect\u00e1culo memorable.<\/p>\n\n\n\n<p>La presencia musical de <strong>Juan Carlos Coronel<\/strong>, con su talento y trayectoria, elev\u00f3 la emotividad de la velada. Sus interpretaciones acompa\u00f1aron los momentos m\u00e1s significativos, desde los desfiles hasta la coronaci\u00f3n, consolid\u00e1ndolo una vez m\u00e1s como uno de los grandes protagonistas art\u00edsticos del Concurso Nacional de Belleza\u00ae.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un certamen que contin\u00faa dejando legado<\/strong><\/h2>\n\n\n\n<p>El concurso no solo coron\u00f3 a una nueva soberana; tambi\u00e9n reafirm\u00f3 la importancia del rol de la mujer colombiana como embajadora de liderazgo, diversidad y sensibilidad social. Las exreinas encargadas de la elecci\u00f3n reforzaron con su presencia el valor hist\u00f3rico del certamen y su vigencia en el pa\u00eds.<\/p>\n\n\n\n<p><strong>La elecci\u00f3n de Mar\u00eda Antonia Mosquera marca el inicio de un nuevo cap\u00edtulo para el Concurso Nacional de Belleza\u00ae<\/strong>, con una soberana que promete representar con fuerza y dedicaci\u00f3n a Colombia durante el periodo 2025-2026. Su triunfo conecta generaciones, regiones y emociones que se unen alrededor de uno de los eventos m\u00e1s emblem\u00e1ticos del pa\u00eds. <\/p>\n\n\n\n<p>Con un p\u00f3dium que enlaza la Costa Atl\u00e1ntica con las costas del Pac\u00edfico y una producci\u00f3n que brill\u00f3 por su calidad, la velada se consolida como un hito m\u00e1s en la historia del certamen. La nueva reina inicia as\u00ed su camino de representaci\u00f3n, inspirada por su familia, respaldada por su departamento y celebrada por todo un pa\u00eds.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-9-16 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Mar\u00eda Antonia Mosquera reina que emociona a Colombia\" width=\"422\" height=\"750\" src=\"https:\/\/www.youtube.com\/embed\/T0y8RRM8LmY?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mar\u00eda Antonia Mosquera agradece emocionada y representa con orgullo al Valle tras ser elegida reina de Colombia 2025-2026, en un certamen poderoso que resalta tradici\u00f3n, belleza y liderazgo nacional<\/p>\n","protected":false},"author":2,"featured_media":11731,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[114,102],"tags":[579,959,160,958,578],"class_list":["post-11730","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-generales","tag-cnb","tag-concurso-nacional-belleza","tag-podcast","tag-senorita-colombia","tag-srta-colombia"],"_links":{"self":[{"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/posts\/11730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/comments?post=11730"}],"version-history":[{"count":4,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/posts\/11730\/revisions"}],"predecessor-version":[{"id":11738,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/posts\/11730\/revisions\/11738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/media\/11731"}],"wp:attachment":[{"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/media?parent=11730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/categories?post=11730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cartagenaaldia.com\/index.php\/wp-json\/wp\/v2\/tags?post=11730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}